{"id":3940,"date":"2026-04-28T05:00:19","date_gmt":"2026-04-28T12:00:19","guid":{"rendered":"https:\/\/www.vailhealth.org\/services\/urgent-care\/dillon-urgent-care\/"},"modified":"2026-05-15T07:18:36","modified_gmt":"2026-05-15T14:18:36","slug":"atencion-de-urgencia-dillon","status":"publish","type":"service","link":"https:\/\/www.vailhealth.org\/es\/services\/urgent-care\/dillon-urgent-care\/","title":{"rendered":"Atenci\u00f3n de Urgencias Dillon"},"content":{"rendered":"<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Un servicio de Colorado Mountain Medical<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tel\u00e9fono <a href=\"tel:(970) 949-6100\">(970) 949-6100<\/a> Fax: (970) 926-6348<br> <br> Centro de Salud Dillon<br> <a href=\"https:\/\/goo.gl\/maps\/145EHEabGziFjWt78\" target=\"_blank\">365 Dillon Ridge Road, Dillon, CO 80435<\/a> Suite 1200<br> <br> Lunes \u2013 Viernes: 8:00 am \u2013 6:00 pm<br> S\u00e1bado: 8:00 a. m. \u2013 5:00 p. m.<br> Domingo: 10:00 a. m. \u2013 4:00 p. m.<br> Feriados: Abierto<br> <br> <strong><em>Aceptamos pacientes sin cita. Por favor, no llame antes de su llegada. Dillon Urgent Care est\u00e1 ubicado en el nivel intermedio (primer piso) del Dillon Health Center, Suite 1200. <\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.cmmhealth.org\/\"><strong>Colorado Mountain Medical, Dillon<\/strong><\/a><br> Colorado Mountain Medical ofrece una gama completa de servicios m\u00e9dicos desde nuestra cl\u00ednica en Dillon. Los pacientes tienen acceso a atenci\u00f3n familiar total, desde medicina preventiva y de bienestar hasta atenci\u00f3n especializada para el tratamiento de lesiones o enfermedades. Ya sea que sea residente local o visitante de nuestras \u00e1reas tur\u00edsticas, encontrar\u00e1 acceso a atenci\u00f3n m\u00e9dica de la m\u00e1s alta calidad en Colorado Mountain Medical.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Este lugar es oficialmente libre de humo y libre de tabaco. Eso significa que fumar cigarrillos, cigarrillos electr\u00f3nicos y vapear est\u00e1 prohibido en todas las \u00e1reas de nuestro campus.<\/em><\/p>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">\u00bfSala de emergencias o atenci\u00f3n de urgencia?<\/h2>\n\n\n\n<section \tclass=\"accordion\"\n\tstyle=\"--padding: 6rem\">\n\t<div class=\"accordion__container container aligncenter\">\n\t\t<div class=\"accordion__row justify-content-center\">\n\t\t\t<div class=\"accordion__col col color-scheme-1\">\n\t\t\t\t<!-- Heading & intro content-->\n\t\t\t\t\n\t\t\t\t<!-- Items -->\n\t\t\t\t<div class=\"accordion__items\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion__item text-align-left\">\n\t\t\t\t\t\t\t<h3 class=\"accordion__item-title\">\n\t\t\t\t\t\t\t\t<button class=\"accordion__item-trigger flex-row align-items-center justify-content-space-between text-align-left\" aria-expanded=\"false\" aria-controls=\"block_763714d4b3d01db594ea41ddd6d07ca5_accordion-panel-1\" id=\"block_763714d4b3d01db594ea41ddd6d07ca5_accordion-title-1\">\n\t\t\t\t\t\t\t\t\t<span>Cu\u00e1ndo llamar al 911<\/span>\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" class=\"plus\"><path d=\"M5 12h14\" \/><path class=\"plus_v\" d=\"M12 5v14\" \/><\/svg>\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t\t\t<div class=\"accordion__item-panel\" id=\"block_763714d4b3d01db594ea41ddd6d07ca5_accordion-panel-1\" role=\"region\" aria-labelledby=\"block_763714d4b3d01db594ea41ddd6d07ca5_accordion-title-1\">\n\t\t\t\t\t\t\t\t<div class=\"accordion__item-panel-content\">\n\t\t\t\t\t\t\t\t\t<p>En caso de una emergencia m\u00e9dica, llama al 911. Los param\u00e9dicos pueden administrar tratamiento vital en el camino al hospital.<\/p>\n<ul>\n<li>S\u00edntomas de ataque card\u00edaco<\/li>\n<li>Traumatismo craneoencef\u00e1lico o fractura de cr\u00e1neo<\/li>\n<li>P\u00e9rdida de visi\u00f3n o de conocimiento<\/li>\n<li>Dolor intenso en el pecho o el abdomen<\/li>\n<li>quemaduras graves, laceraciones o hemorragias<\/li>\n<li>Dificultad para respirar<\/li>\n<li>S\u00edntomas de un derrame cerebral<\/li>\n<\/ul>\n<p>Por favor, tenga en cuenta que los ni\u00f1os pueden presentar s\u00edntomas diferentes a los de los adultos. Busque siempre atenci\u00f3n m\u00e9dica inmediata si cree que un ni\u00f1o est\u00e1 experimentando una emergencia m\u00e9dica.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion__item text-align-left\">\n\t\t\t\t\t\t\t<h3 class=\"accordion__item-title\">\n\t\t\t\t\t\t\t\t<button class=\"accordion__item-trigger flex-row align-items-center justify-content-space-between text-align-left\" aria-expanded=\"false\" aria-controls=\"block_763714d4b3d01db594ea41ddd6d07ca5_accordion-panel-2\" id=\"block_763714d4b3d01db594ea41ddd6d07ca5_accordion-title-2\">\n\t\t\t\t\t\t\t\t\t<span>Cu\u00e1ndo visitar un centro de atenci\u00f3n de urgencias<\/span>\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" class=\"plus\"><path d=\"M5 12h14\" \/><path class=\"plus_v\" d=\"M12 5v14\" \/><\/svg>\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t\t\t<div class=\"accordion__item-panel\" id=\"block_763714d4b3d01db594ea41ddd6d07ca5_accordion-panel-2\" role=\"region\" aria-labelledby=\"block_763714d4b3d01db594ea41ddd6d07ca5_accordion-title-2\">\n\t\t\t\t\t\t\t\t<div class=\"accordion__item-panel-content\">\n\t\t\t\t\t\t\t\t\t<p>Las cl\u00ednicas de atenci\u00f3n de urgencia son un gran recurso si su m\u00e9dico de cabecera no est\u00e1 disponible. Tratan los siguientes s\u00edntomas m\u00e9dicos de inmediato.<\/p>\n<ul>\n<li>Mal de altura y deshidrataci\u00f3n<\/li>\n<li>Alergias<\/li>\n<li>Dolor de espalda<\/li>\n<li>Tos, Resfriado, Gripe, Dolor de garganta, Faringitis estreptoc\u00f3cica<\/li>\n<li>Dolor de o\u00eddo<\/li>\n<li>Infecciones menores: Infecci\u00f3n del tracto urinario, Infecci\u00f3n de las v\u00edas respiratorias altas, Infecci\u00f3n de los senos paranasales<\/li>\n<li>Migra\u00f1a<\/li>\n<li>Cortes menores, laceraciones y quemaduras<\/li>\n<li>Reacciones al\u00e9rgicas leves<\/li>\n<li>Lesiones Menores de Huesos y Articulaciones<\/li>\n<li>Erupci\u00f3n<\/li>\n<li>Problemas estomacales leves, v\u00f3mitos, diarrea y deshidrataci\u00f3n<\/li>\n<li>Sangrado y\/o flujo vaginal<\/li>\n<\/ul>\n<p>Por favor, tenga en cuenta que los ni\u00f1os pueden presentar s\u00edntomas diferentes a los de los adultos. Busque siempre atenci\u00f3n m\u00e9dica inmediata si cree que un ni\u00f1o est\u00e1 experimentando una emergencia m\u00e9dica.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion__item text-align-left\">\n\t\t\t\t\t\t\t<h3 class=\"accordion__item-title\">\n\t\t\t\t\t\t\t\t<button class=\"accordion__item-trigger flex-row align-items-center justify-content-space-between text-align-left\" aria-expanded=\"false\" aria-controls=\"block_763714d4b3d01db594ea41ddd6d07ca5_accordion-panel-3\" id=\"block_763714d4b3d01db594ea41ddd6d07ca5_accordion-title-3\">\n\t\t\t\t\t\t\t\t\t<span>Cu\u00e1ndo visitar la sala de emergencias<\/span>\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" class=\"plus\"><path d=\"M5 12h14\" \/><path class=\"plus_v\" d=\"M12 5v14\" \/><\/svg>\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t\t\t<div class=\"accordion__item-panel\" id=\"block_763714d4b3d01db594ea41ddd6d07ca5_accordion-panel-3\" role=\"region\" aria-labelledby=\"block_763714d4b3d01db594ea41ddd6d07ca5_accordion-title-3\">\n\t\t\t\t\t\t\t\t<div class=\"accordion__item-panel-content\">\n\t\t\t\t\t\t\t\t\t<p>Los siguientes s\u00edntomas se eval\u00faan mejor en un Departamento de Emergencias.<\/p>\n<ul>\n<li>Dolor persistente en el pecho, especialmente si se irradia al brazo o la mand\u00edbula, o si se acompa\u00f1a de sudoraci\u00f3n, v\u00f3mitos<\/li>\n<li>Dolor o presi\u00f3n en el pecho o abdomen superior<\/li>\n<li>Dificultad para respirar, falta de aire<\/li>\n<li>Confusi\u00f3n o cambios en el estado mental, incluyendo pensamientos suicidas<\/li>\n<li>Cualquier dolor s\u00fabito o intenso, especialmente en el abdomen o que empiece a mitad de la espalda.<\/li>\n<li>Torpeza repentina, p\u00e9rdida del equilibrio, desmayos o mareos<\/li>\n<li>Dificultad repentina para hablar, o problemas para entender el habla<\/li>\n<li>Debilidad o par\u00e1lisis repentina, especialmente en un lado de la cara o del cuerpo<\/li>\n<li>Palpitaciones card\u00edacas severas<\/li>\n<li>Dolor de cabeza repentino e intenso<\/li>\n<li>Dolor e hinchaz\u00f3n testicular repentinos<\/li>\n<li>Beb\u00e9 reci\u00e9n nacido con fiebre (un beb\u00e9 menor de tres meses con una temperatura de 38 grados Celsius o superior necesita ser examinado de inmediato)<\/li>\n<li>Ca\u00eddas que causan lesiones o que ocurren mientras se toman medicamentos anticoagulantes<\/li>\n<li>Cambios repentinos en la visi\u00f3n, incluyendo visi\u00f3n borrosa o doble y p\u00e9rdida total o parcial de la visi\u00f3n<\/li>\n<li>Fracturas de huesos o dislocaci\u00f3n de articulaciones<\/li>\n<li>Cortes profundos que requieren puntadas \u2014 especialmente en la cara \u2014 o una herida abierta grande que no deja de sangrar<\/li>\n<li>Lesiones en la cabeza o en los ojos<\/li>\n<li>S\u00edntomas severos de gripe o resfriado<\/li>\n<li>Fiebres altas o fiebres con sarpullido<\/li>\n<li>Sangrado vaginal durante el embarazo<\/li>\n<li>V\u00f3mitos o diarrea intensos y persistentes<\/li>\n<li>Quemaduras graves<\/li>\n<li>Convulsiones sin un diagn\u00f3stico previo de epilepsia<\/li>\n<li>Sangre en las heces o en la orina<\/li>\n<li>Hemorragia descontrolada<\/li>\n<li>Toser o vomitar sangre<\/li>\n<li>Infecci\u00f3n con s\u00edntomas graves<\/li>\n<li>Atenci\u00f3n fuera de horario para enfermedades o lesiones leves si no hay otra opci\u00f3n disponible<\/li>\n<\/ul>\n<p>Por favor, tenga en cuenta que los ni\u00f1os pueden presentar s\u00edntomas diferentes a los de los adultos. Busque siempre atenci\u00f3n m\u00e9dica inmediata si cree que un ni\u00f1o est\u00e1 experimentando una emergencia m\u00e9dica.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div> <!-- .accordion__items -->\n\t\t\t<\/div> <!-- .accordion__col.col -->\n\t\t<\/div> <!-- .accordion__row.row -->\n\t<\/div> <!-- .accordion__container.container -->\n<\/section> <!-- .accordion -->\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Precios de Servicios de Atenci\u00f3n de Urgencia y CMM<\/h2>\n<\/div>\n\n\n\n<section \tclass=\"accordion\"\n\tstyle=\"--padding: 6rem\">\n\t<div class=\"accordion__container container aligncenter\">\n\t\t<div class=\"accordion__row justify-content-center\">\n\t\t\t<div class=\"accordion__col col color-scheme-1\">\n\t\t\t\t<!-- Heading & intro content-->\n\t\t\t\t\n\t\t\t\t<!-- Items -->\n\t\t\t\t<div class=\"accordion__items\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion__item text-align-left\">\n\t\t\t\t\t\t\t<h3 class=\"accordion__item-title\">\n\t\t\t\t\t\t\t\t<button class=\"accordion__item-trigger flex-row align-items-center justify-content-space-between text-align-left\" aria-expanded=\"false\" aria-controls=\"block_c2e6239f15f0c616fc69f45aacde12be_accordion-panel-1\" id=\"block_c2e6239f15f0c616fc69f45aacde12be_accordion-title-1\">\n\t\t\t\t\t\t\t\t\t<span>Precios de Urgencias<\/span>\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" class=\"plus\"><path d=\"M5 12h14\" \/><path class=\"plus_v\" d=\"M12 5v14\" \/><\/svg>\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t\t\t<div class=\"accordion__item-panel\" id=\"block_c2e6239f15f0c616fc69f45aacde12be_accordion-panel-1\" role=\"region\" aria-labelledby=\"block_c2e6239f15f0c616fc69f45aacde12be_accordion-title-1\">\n\t\t\t\t\t\t\t\t<div class=\"accordion__item-panel-content\">\n\t\t\t\t\t\t\t\t\t<p>Por favor visita el\u00a0<a href=\"https:\/\/www.cmmhealth.org\/patient-resources\/charges-and-fees\" target=\"_blank\" rel=\"noopener\">P\u00e1gina de Cargos y Tarifas en el sitio web de Colorado Mountain Medical<\/a>\u00a0para toda la informaci\u00f3n de precios.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion__item text-align-left\">\n\t\t\t\t\t\t\t<h3 class=\"accordion__item-title\">\n\t\t\t\t\t\t\t\t<button class=\"accordion__item-trigger flex-row align-items-center justify-content-space-between text-align-left\" aria-expanded=\"false\" aria-controls=\"block_c2e6239f15f0c616fc69f45aacde12be_accordion-panel-2\" id=\"block_c2e6239f15f0c616fc69f45aacde12be_accordion-title-2\">\n\t\t\t\t\t\t\t\t\t<span>Facturaci\u00f3n y Seguros<\/span>\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" class=\"plus\"><path d=\"M5 12h14\" \/><path class=\"plus_v\" d=\"M12 5v14\" \/><\/svg>\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t\t\t<div class=\"accordion__item-panel\" id=\"block_c2e6239f15f0c616fc69f45aacde12be_accordion-panel-2\" role=\"region\" aria-labelledby=\"block_c2e6239f15f0c616fc69f45aacde12be_accordion-title-2\">\n\t\t\t\t\t\t\t\t<div class=\"accordion__item-panel-content\">\n\t\t\t\t\t\t\t\t\t<p>Por favor visita el\u00a0<a href=\"https:\/\/www.cmmhealth.org\/patient-resources\/billing-and-insurance\" target=\"_blank\" rel=\"noopener\">P\u00e1gina de facturaci\u00f3n y seguros en el sitio web de Colorado Mountain Medical\u00a0<\/a>para aprender m\u00e1s.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion__item text-align-left\">\n\t\t\t\t\t\t\t<h3 class=\"accordion__item-title\">\n\t\t\t\t\t\t\t\t<button class=\"accordion__item-trigger flex-row align-items-center justify-content-space-between text-align-left\" aria-expanded=\"false\" aria-controls=\"block_c2e6239f15f0c616fc69f45aacde12be_accordion-panel-3\" id=\"block_c2e6239f15f0c616fc69f45aacde12be_accordion-title-3\">\n\t\t\t\t\t\t\t\t\t<span>Pol\u00edtica de descuentos 15%<\/span>\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" class=\"plus\"><path d=\"M5 12h14\" \/><path class=\"plus_v\" d=\"M12 5v14\" \/><\/svg>\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t\t\t<div class=\"accordion__item-panel\" id=\"block_c2e6239f15f0c616fc69f45aacde12be_accordion-panel-3\" role=\"region\" aria-labelledby=\"block_c2e6239f15f0c616fc69f45aacde12be_accordion-title-3\">\n\t\t\t\t\t\t\t\t<div class=\"accordion__item-panel-content\">\n\t\t\t\t\t\t\t\t\t<p>Para quienes no tienen seguro m\u00e9dico o deciden no utilizarlo, Colorado Mountain Medical ofrece un descuento 15% para pagos por cuenta propia en todos sus centros, destinado a aquellas personas que puedan abonar el importe total en el momento de recibir el servicio.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div> <!-- .accordion__items -->\n\t\t\t<\/div> <!-- .accordion__col.col -->\n\t\t<\/div> <!-- .accordion__row.row -->\n\t<\/div> <!-- .accordion__container.container -->\n<\/section> <!-- .accordion -->\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"featured_media":3941,"parent":2807,"menu_order":0,"template":"","meta":{"_acf_changed":true},"class_list":["post-3940","service","type-service","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dillon Urgent Care | Vail Health<\/title>\n<meta name=\"description\" content=\"Meet the providers connected to Vail Health and our service lines.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vailhealth.org\/es\/servicios\/atencion-de-urgencia\/atencion-de-urgencia-dillon\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dillon Urgent Care | Vail Health\" \/>\n<meta property=\"og:description\" content=\"Meet the providers connected to Vail Health and our service lines.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vailhealth.org\/es\/servicios\/atencion-de-urgencia\/atencion-de-urgencia-dillon\/\" \/>\n<meta property=\"og:site_name\" content=\"Vail Health\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VailHealth\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-15T14:18:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2026\/04\/Dillon-Health-Center-Exterior-4x3_reg-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/services\\\/urgent-care\\\/dillon-urgent-care\\\/\",\"url\":\"https:\\\/\\\/www.vailhealth.org\\\/services\\\/urgent-care\\\/dillon-urgent-care\\\/\",\"name\":\"Dillon Urgent Care | Vail Health\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/services\\\/urgent-care\\\/dillon-urgent-care\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/services\\\/urgent-care\\\/dillon-urgent-care\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vailhealth.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Dillon-Health-Center-Exterior-4x3_reg-3.jpg\",\"datePublished\":\"2026-04-28T12:00:19+00:00\",\"dateModified\":\"2026-05-15T14:18:36+00:00\",\"description\":\"Meet the providers connected to Vail Health and our service lines.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/services\\\/urgent-care\\\/dillon-urgent-care\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vailhealth.org\\\/services\\\/urgent-care\\\/dillon-urgent-care\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/services\\\/urgent-care\\\/dillon-urgent-care\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vailhealth.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Dillon-Health-Center-Exterior-4x3_reg-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vailhealth.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Dillon-Health-Center-Exterior-4x3_reg-3.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/services\\\/urgent-care\\\/dillon-urgent-care\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vailhealth.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\\\/\\\/www.vailhealth.org\\\/services\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Urgent Care\",\"item\":\"https:\\\/\\\/www.vailhealth.org\\\/services\\\/urgent-care\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Dillon Urgent Care\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/#website\",\"url\":\"https:\\\/\\\/www.vailhealth.org\\\/\",\"name\":\"Vail Health\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vailhealth.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/#organization\",\"name\":\"Vail Health\",\"url\":\"https:\\\/\\\/www.vailhealth.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vailhealth.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/layouthorizontal-colorfull.png\",\"contentUrl\":\"https:\\\/\\\/www.vailhealth.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/layouthorizontal-colorfull.png\",\"width\":341,\"height\":64,\"caption\":\"Vail Health\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VailHealth\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dillon Urgent Care | Vail Health","description":"Conozca a los proveedores conectados a Vail Health y a nuestras l\u00edneas de servicio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vailhealth.org\/es\/servicios\/atencion-de-urgencia\/atencion-de-urgencia-dillon\/","og_locale":"es_MX","og_type":"article","og_title":"Dillon Urgent Care | Vail Health","og_description":"Meet the providers connected to Vail Health and our service lines.","og_url":"https:\/\/www.vailhealth.org\/es\/servicios\/atencion-de-urgencia\/atencion-de-urgencia-dillon\/","og_site_name":"Vail Health","article_publisher":"https:\/\/www.facebook.com\/VailHealth\/","article_modified_time":"2026-05-15T14:18:36+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2026\/04\/Dillon-Health-Center-Exterior-4x3_reg-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vailhealth.org\/services\/urgent-care\/dillon-urgent-care\/","url":"https:\/\/www.vailhealth.org\/services\/urgent-care\/dillon-urgent-care\/","name":"Dillon Urgent Care | Vail Health","isPartOf":{"@id":"https:\/\/www.vailhealth.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vailhealth.org\/services\/urgent-care\/dillon-urgent-care\/#primaryimage"},"image":{"@id":"https:\/\/www.vailhealth.org\/services\/urgent-care\/dillon-urgent-care\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2026\/04\/Dillon-Health-Center-Exterior-4x3_reg-3.jpg","datePublished":"2026-04-28T12:00:19+00:00","dateModified":"2026-05-15T14:18:36+00:00","description":"Conozca a los proveedores conectados a Vail Health y a nuestras l\u00edneas de servicio.","breadcrumb":{"@id":"https:\/\/www.vailhealth.org\/services\/urgent-care\/dillon-urgent-care\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vailhealth.org\/services\/urgent-care\/dillon-urgent-care\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.vailhealth.org\/services\/urgent-care\/dillon-urgent-care\/#primaryimage","url":"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2026\/04\/Dillon-Health-Center-Exterior-4x3_reg-3.jpg","contentUrl":"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2026\/04\/Dillon-Health-Center-Exterior-4x3_reg-3.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.vailhealth.org\/services\/urgent-care\/dillon-urgent-care\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vailhealth.org\/"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/www.vailhealth.org\/services\/"},{"@type":"ListItem","position":3,"name":"Urgent Care","item":"https:\/\/www.vailhealth.org\/services\/urgent-care\/"},{"@type":"ListItem","position":4,"name":"Dillon Urgent Care"}]},{"@type":"WebSite","@id":"https:\/\/www.vailhealth.org\/#website","url":"https:\/\/www.vailhealth.org\/","name":"Vail Salud","description":"","publisher":{"@id":"https:\/\/www.vailhealth.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vailhealth.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.vailhealth.org\/#organization","name":"Vail Salud","url":"https:\/\/www.vailhealth.org\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.vailhealth.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2026\/03\/layouthorizontal-colorfull.png","contentUrl":"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2026\/03\/layouthorizontal-colorfull.png","width":341,"height":64,"caption":"Vail Health"},"image":{"@id":"https:\/\/www.vailhealth.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VailHealth\/"]}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Vail Health","distributor_original_site_url":"https:\/\/www.vailhealth.org\/es","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/services\/3940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/services"}],"about":[{"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/types\/service"}],"up":[{"embeddable":true,"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/services\/2807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/media\/3941"}],"wp:attachment":[{"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/media?parent=3940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}