{"id":1262,"date":"2017-01-03T00:00:00","date_gmt":"2017-01-03T07:00:00","guid":{"rendered":"https:\/\/www.vailhealth.org\/5-foods-to-reduce-stress\/"},"modified":"2017-01-03T00:00:00","modified_gmt":"2017-01-03T07:00:00","slug":"5-alimentos-para-reducir-el-estres","status":"publish","type":"post","link":"https:\/\/www.vailhealth.org\/es\/news\/5-foods-to-reduce-stress\/","title":{"rendered":"5 alimentos para reducir el estr\u00e9s"},"content":{"rendered":"<p class=\"wp-block-paragraph\">El estr\u00e9s a menudo te hace pensar en alimentos reconfortantes y puede aumentar tu apetito. Cuando consumes alimentos azucarados, salados y fritos, puedes experimentar un pico temporal que te hace sentir bien, pero que puede llevarte a un ciclo de bajones y atracones posteriores de m\u00e1s comida chatarra. Muchas personas se quejan de aumento de peso durante situaciones estresantes, especialmente si son a largo plazo, como cuidar a un ser querido o pasar por un divorcio. As\u00ed que reconsideremos nuestra alimentaci\u00f3n por estr\u00e9s y busquemos alimentos que realmente combatan el estr\u00e9s y mejoren la salud.<\/p>\n\n\n<p class=\"wp-block-paragraph\">Primero que nada, \u00bfqu\u00e9 es el estr\u00e9s? El estr\u00e9s es la forma en que nuestros cuerpos reaccionan ante una amenaza o un desaf\u00edo. Puede ser a corto plazo, como escapar de un accidente automovil\u00edstico, o a largo plazo, como un trabajo exigente. Cuando nuestros cuerpos se ven amenazados, nuestro sistema nervioso simp\u00e1tico libera cortisol, adrenalina y noradrenalina. Estas hormonas crean nuestra respuesta de \"lucha o huida\", lo que lleva a un aumento de la presi\u00f3n arterial, de la frecuencia card\u00edaca y a una respiraci\u00f3n r\u00e1pida. Disminuye las funciones corporales no esenciales, como la ralentizaci\u00f3n del sistema digestivo y del sistema inmunol\u00f3gico. Nuestros m\u00fasculos pueden tensarse y el ciclo de sue\u00f1o puede verse afectado (aumento del estado de alerta). El estr\u00e9s es una parte normal de nuestra supervivencia, pero puede aumentar enormemente los riesgos para la salud si no lo manejamos bien. Por ejemplo, seg\u00fan la Dra. Almeida, una destacada investigadora del estr\u00e9s en Penn State, tener una mala actitud hacia nuestras listas de tareas pendientes duplica el riesgo de ataque card\u00edaco en comparaci\u00f3n con aquellos que tienen una actitud m\u00e1s relajada.<\/p>\n\n\n<p class=\"wp-block-paragraph\">Llevar una dieta saludable es una forma importante de combatir el estr\u00e9s. La importancia debe centrarse en los nutrientes que reducen la inflamaci\u00f3n y disminuyen el cortisol. Aqu\u00ed tienes cinco de los mejores nutrientes para combatir el estr\u00e9s y d\u00f3nde encontrarlos.<\/p>\n\n\n<ol class=\"wp-block-list\">\n<li>Magnesio: Equilibra los niveles de cortisol. Las mejores fuentes incluyen semillas de calabaza, espinacas, frijoles negros, quinua y anacardos.<\/li>\n\n\n<li>Vitaminas B \u2013 B6, B12, Folato \u2013 Las vitaminas B son cofactores importantes para muchas reacciones enzim\u00e1ticas en nuestro cuerpo. Son responsables de la producci\u00f3n de energ\u00eda, la cual puede combatir la fatiga y es vital para la salud cerebral, la memoria y la funci\u00f3n cognitiva, que pueden deprimirse por el estr\u00e9s. Tambi\u00e9n se utilizan para disminuir los niveles de homociste\u00edna, reduciendo el riesgo de ataque card\u00edaco. Las deficiencias de estas vitaminas pueden dificultar el manejo del estr\u00e9s.\n<ul>\n<li>a. B6 \u2013 aves y pescado, espinacas, pl\u00e1tanos y batatas.<\/li>\n<li>b. B12 \u2013 Cereales fortificados y alternativas a la leche, y alimentos de origen animal como pescado, aves de corral y l\u00e1cteos.<\/li>\n<li>c. Folato: lentejas y otras legumbres, esp\u00e1rragos y verduras de hoja verde oscuro.<\/li>\n<\/ul><\/li>\n\n\n<li>Vitamina C: Ralentiza la producci\u00f3n de cortisol \u2013 Las mejores fuentes incluyen casi todas las frutas y verduras, frutas c\u00edtricas, kiwis y verduras de hoja verde oscuro.<\/li>\n\n\n<li>\u00c1cidos grasos Omega-3: reducen la inflamaci\u00f3n general del cuerpo y son un buen antioxidante. Tambi\u00e9n disminuyen los niveles de cortisol y pueden hacer que te sientas menos estresado. Fuentes de Omega-3: incluyen pescados grasos, nueces, semillas de lino y soya.<\/li>\n\n\n<li>Zinc \u2013 inhibe la secreci\u00f3n de cortisol y potencia el sistema inmunol\u00f3gico. Las fuentes de zinc incluyen aves de corral, vegetales de hoja verde oscuro, legumbres y esp\u00e1rragos.<\/li>\n\n<\/ol>\n\n\n<p class=\"wp-block-paragraph\">Otras t\u00e9cnicas para aliviar el estr\u00e9s son hacer ejercicio regularmente, meditar, recibir masajes y practicar yoga. Incluso solo respirar conscientemente puede ayudar a liberar endorfinas que nos hacen sentir bien y reducir el estr\u00e9s.<\/p>\n\n\n<p class=\"wp-block-paragraph\">Melaine Hendershott MS, RDN, CSO. Para consultar con Melaine, por favor llame al (970) 569-7614 o cont\u00e1ctela en <a href=\"mailto:hendershott@vvmc.com\" target=\"_top\">hendershott@vvmc.com<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Stress often makes you think of comfort foods and can increase your appetite. When you&#8217;re eating sugary, salty, and fried foods you can get a temporary high that makes you feel good but can leave you spiraling and crashing afterwards leading to more junk food binges. Many people complain of weight gain during stressful situations,&#8230;<\/p>","protected":false},"author":0,"featured_media":1263,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1262","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5 Foods to Reduce Stress | Vail Health<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vailhealth.org\/es\/noticias\/5-alimentos-para-reducir-el-estres\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 Foods to Reduce Stress | Vail Health\" \/>\n<meta property=\"og:description\" content=\"Stress often makes you think of comfort foods and can increase your appetite. When you&#8217;re eating sugary, salty, and fried foods you can get a temporary high that makes you feel good but can leave you spiraling and crashing afterwards leading to more junk food binges. Many people complain of weight gain during stressful situations,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vailhealth.org\/es\/noticias\/5-alimentos-para-reducir-el-estres\/\" \/>\n<meta property=\"og:site_name\" content=\"Vail Health\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VailHealth\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-03T07:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2017\/01\/melaine_reg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"238\" \/>\n\t<meta property=\"og:image:height\" content=\"158\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/news\\\/5-foods-to-reduce-stress\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/news\\\/5-foods-to-reduce-stress\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"5 Foods to Reduce Stress\",\"datePublished\":\"2017-01-03T07:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/news\\\/5-foods-to-reduce-stress\\\/\"},\"wordCount\":527,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/news\\\/5-foods-to-reduce-stress\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vailhealth.org\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/melaine_reg.jpg\",\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vailhealth.org\\\/news\\\/5-foods-to-reduce-stress\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/news\\\/5-foods-to-reduce-stress\\\/\",\"url\":\"https:\\\/\\\/www.vailhealth.org\\\/news\\\/5-foods-to-reduce-stress\\\/\",\"name\":\"5 Foods to Reduce Stress | Vail Health\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/news\\\/5-foods-to-reduce-stress\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/news\\\/5-foods-to-reduce-stress\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vailhealth.org\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/melaine_reg.jpg\",\"datePublished\":\"2017-01-03T07:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/news\\\/5-foods-to-reduce-stress\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vailhealth.org\\\/news\\\/5-foods-to-reduce-stress\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/news\\\/5-foods-to-reduce-stress\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vailhealth.org\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/melaine_reg.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vailhealth.org\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/melaine_reg.jpg\",\"width\":238,\"height\":158},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/news\\\/5-foods-to-reduce-stress\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vailhealth.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 Foods to Reduce Stress\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/#website\",\"url\":\"https:\\\/\\\/www.vailhealth.org\\\/\",\"name\":\"Vail Health\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vailhealth.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/#organization\",\"name\":\"Vail Health\",\"url\":\"https:\\\/\\\/www.vailhealth.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vailhealth.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/layouthorizontal-colorfull.png\",\"contentUrl\":\"https:\\\/\\\/www.vailhealth.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/layouthorizontal-colorfull.png\",\"width\":341,\"height\":64,\"caption\":\"Vail Health\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VailHealth\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 Alimentos para Reducir el Estr\u00e9s | Vail Health","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vailhealth.org\/es\/noticias\/5-alimentos-para-reducir-el-estres\/","og_locale":"es_MX","og_type":"article","og_title":"5 Foods to Reduce Stress | Vail Health","og_description":"Stress often makes you think of comfort foods and can increase your appetite. When you&#8217;re eating sugary, salty, and fried foods you can get a temporary high that makes you feel good but can leave you spiraling and crashing afterwards leading to more junk food binges. Many people complain of weight gain during stressful situations,...","og_url":"https:\/\/www.vailhealth.org\/es\/noticias\/5-alimentos-para-reducir-el-estres\/","og_site_name":"Vail Health","article_publisher":"https:\/\/www.facebook.com\/VailHealth\/","article_published_time":"2017-01-03T07:00:00+00:00","og_image":[{"width":238,"height":158,"url":"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2017\/01\/melaine_reg.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vailhealth.org\/news\/5-foods-to-reduce-stress\/#article","isPartOf":{"@id":"https:\/\/www.vailhealth.org\/news\/5-foods-to-reduce-stress\/"},"author":{"name":"","@id":""},"headline":"5 Foods to Reduce Stress","datePublished":"2017-01-03T07:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vailhealth.org\/news\/5-foods-to-reduce-stress\/"},"wordCount":527,"commentCount":0,"publisher":{"@id":"https:\/\/www.vailhealth.org\/#organization"},"image":{"@id":"https:\/\/www.vailhealth.org\/news\/5-foods-to-reduce-stress\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2017\/01\/melaine_reg.jpg","inLanguage":"es-MX","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vailhealth.org\/news\/5-foods-to-reduce-stress\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vailhealth.org\/news\/5-foods-to-reduce-stress\/","url":"https:\/\/www.vailhealth.org\/news\/5-foods-to-reduce-stress\/","name":"5 Alimentos para Reducir el Estr\u00e9s | Vail Health","isPartOf":{"@id":"https:\/\/www.vailhealth.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vailhealth.org\/news\/5-foods-to-reduce-stress\/#primaryimage"},"image":{"@id":"https:\/\/www.vailhealth.org\/news\/5-foods-to-reduce-stress\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2017\/01\/melaine_reg.jpg","datePublished":"2017-01-03T07:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.vailhealth.org\/news\/5-foods-to-reduce-stress\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vailhealth.org\/news\/5-foods-to-reduce-stress\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.vailhealth.org\/news\/5-foods-to-reduce-stress\/#primaryimage","url":"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2017\/01\/melaine_reg.jpg","contentUrl":"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2017\/01\/melaine_reg.jpg","width":238,"height":158},{"@type":"BreadcrumbList","@id":"https:\/\/www.vailhealth.org\/news\/5-foods-to-reduce-stress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vailhealth.org\/"},{"@type":"ListItem","position":2,"name":"5 Foods to Reduce Stress"}]},{"@type":"WebSite","@id":"https:\/\/www.vailhealth.org\/#website","url":"https:\/\/www.vailhealth.org\/","name":"Vail Salud","description":"","publisher":{"@id":"https:\/\/www.vailhealth.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vailhealth.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.vailhealth.org\/#organization","name":"Vail Salud","url":"https:\/\/www.vailhealth.org\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.vailhealth.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2026\/03\/layouthorizontal-colorfull.png","contentUrl":"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2026\/03\/layouthorizontal-colorfull.png","width":341,"height":64,"caption":"Vail Health"},"image":{"@id":"https:\/\/www.vailhealth.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VailHealth\/"]}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Vail Health","distributor_original_site_url":"https:\/\/www.vailhealth.org\/es","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/posts\/1262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/comments?post=1262"}],"version-history":[{"count":0,"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/posts\/1262\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/media\/1263"}],"wp:attachment":[{"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/media?parent=1262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/categories?post=1262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/tags?post=1262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}