{"id":3617,"date":"2026-04-27T21:30:56","date_gmt":"2026-04-28T04:30:56","guid":{"rendered":"https:\/\/www.vailhealth.org\/staff\/grant-rynn\/"},"modified":"2026-06-01T17:33:46","modified_gmt":"2026-06-02T00:33:46","slug":"grant-rynn","status":"publish","type":"staff","link":"https:\/\/www.vailhealth.org\/es\/about\/doctor-directory\/grant-rynn\/","title":{"rendered":"Grant Rynn"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Grant, que se cri\u00f3 en Denver, siempre quiso vivir en las monta\u00f1as. Antes de estudiar para ser asistente m\u00e9dico, prest\u00f3 servicios de atenci\u00f3n m\u00e9dica de emergencia aqu\u00ed, en el condado de Eagle, desde 2008, primero como t\u00e9cnico de emergencias m\u00e9dicas y luego como param\u00e9dico de cuidados intensivos. Grant se gradu\u00f3 del Programa de Asistentes M\u00e9dicos de la Universidad de Quinnipiac en 2016 y, antes de unirse a Surgical Associates, trabaj\u00f3 como asistente m\u00e9dico en el Departamento de Emergencias de un centro de trauma de nivel 1 en el \u00e1rea metropolitana de Denver.<\/p>\n\n\n<p class=\"wp-block-paragraph\">Grant tiene intereses especiales en el manejo del paciente quir\u00fargico, traum\u00e1tico y cr\u00edticamente enfermo. Es director m\u00e9dico asistente de Vail Ski Patrol y brinda atenci\u00f3n a pacientes enfermos y lesionados en un entorno austero. Se mantiene involucrado con el programa de extensi\u00f3n de trauma de Vail Health para brindar educaci\u00f3n sobre trauma a nuestra comunidad con programas como Stop the Bleed\u00ae.<\/p>\n\n\n<p class=\"wp-block-paragraph\">Cuando no est\u00e1 trabajando, disfruta pasar tiempo con su familia, pescar con mosca, andar en bicicleta de monta\u00f1a, correr y esquiar.<\/p>","protected":false},"featured_media":6347,"template":"","meta":{"_acf_changed":true},"tags":[],"staff-specialties":[24,25],"class_list":["post-3617","staff","type-staff","status-publish","has-post-thumbnail","hentry","staff-specialties-robotic-surgery","staff-specialties-surgery"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grant Rynn | Vail Health<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vailhealth.org\/es\/acerca-de\/directorio-de-doctores\/grant-rynn\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grant Rynn | Vail Health\" \/>\n<meta property=\"og:description\" content=\"Raised in Denver, Grant always wanted to reside in the mountains. Prior to PA school, he provided emergency medical care here in Eagle County since 2008 as an EMT then critical care paramedic. Grant graduated from the Quinnipiac University Physician Assistant Program in 2016 and before joining Surgical Associates he worked as a PA in...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vailhealth.org\/es\/acerca-de\/directorio-de-doctores\/grant-rynn\/\" \/>\n<meta property=\"og:site_name\" content=\"Vail Health\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VailHealth\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-02T00:33:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2026\/04\/VH-web-800x800-GRynn.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/about\\\/doctor-directory\\\/grant-rynn\\\/\",\"url\":\"https:\\\/\\\/www.vailhealth.org\\\/about\\\/doctor-directory\\\/grant-rynn\\\/\",\"name\":\"Grant Rynn | Vail Health\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/about\\\/doctor-directory\\\/grant-rynn\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/about\\\/doctor-directory\\\/grant-rynn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vailhealth.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/VH-web-800x800-GRynn.jpeg\",\"datePublished\":\"2026-04-28T04:30:56+00:00\",\"dateModified\":\"2026-06-02T00:33:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/about\\\/doctor-directory\\\/grant-rynn\\\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vailhealth.org\\\/about\\\/doctor-directory\\\/grant-rynn\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/about\\\/doctor-directory\\\/grant-rynn\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vailhealth.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/VH-web-800x800-GRynn.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.vailhealth.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/VH-web-800x800-GRynn.jpeg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/about\\\/doctor-directory\\\/grant-rynn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vailhealth.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Staff \\\/ Providers\",\"item\":\"https:\\\/\\\/www.vailhealth.org\\\/about\\\/doctor-directory\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Grant Rynn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/#website\",\"url\":\"https:\\\/\\\/www.vailhealth.org\\\/\",\"name\":\"Vail Health\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vailhealth.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/#organization\",\"name\":\"Vail Health\",\"url\":\"https:\\\/\\\/www.vailhealth.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vailhealth.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/layouthorizontal-colorfull.png\",\"contentUrl\":\"https:\\\/\\\/www.vailhealth.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/layouthorizontal-colorfull.png\",\"width\":341,\"height\":64,\"caption\":\"Vail Health\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vailhealth.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VailHealth\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grant Rynn | Vail Health","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vailhealth.org\/es\/acerca-de\/directorio-de-doctores\/grant-rynn\/","og_locale":"es_MX","og_type":"article","og_title":"Grant Rynn | Vail Health","og_description":"Raised in Denver, Grant always wanted to reside in the mountains. Prior to PA school, he provided emergency medical care here in Eagle County since 2008 as an EMT then critical care paramedic. Grant graduated from the Quinnipiac University Physician Assistant Program in 2016 and before joining Surgical Associates he worked as a PA in...","og_url":"https:\/\/www.vailhealth.org\/es\/acerca-de\/directorio-de-doctores\/grant-rynn\/","og_site_name":"Vail Health","article_publisher":"https:\/\/www.facebook.com\/VailHealth\/","article_modified_time":"2026-06-02T00:33:46+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2026\/04\/VH-web-800x800-GRynn.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vailhealth.org\/about\/doctor-directory\/grant-rynn\/","url":"https:\/\/www.vailhealth.org\/about\/doctor-directory\/grant-rynn\/","name":"Grant Rynn | Vail Health","isPartOf":{"@id":"https:\/\/www.vailhealth.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vailhealth.org\/about\/doctor-directory\/grant-rynn\/#primaryimage"},"image":{"@id":"https:\/\/www.vailhealth.org\/about\/doctor-directory\/grant-rynn\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2026\/04\/VH-web-800x800-GRynn.jpeg","datePublished":"2026-04-28T04:30:56+00:00","dateModified":"2026-06-02T00:33:46+00:00","breadcrumb":{"@id":"https:\/\/www.vailhealth.org\/about\/doctor-directory\/grant-rynn\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vailhealth.org\/about\/doctor-directory\/grant-rynn\/"]}]},{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.vailhealth.org\/about\/doctor-directory\/grant-rynn\/#primaryimage","url":"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2026\/04\/VH-web-800x800-GRynn.jpeg","contentUrl":"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2026\/04\/VH-web-800x800-GRynn.jpeg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vailhealth.org\/about\/doctor-directory\/grant-rynn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vailhealth.org\/"},{"@type":"ListItem","position":2,"name":"Staff \/ Providers","item":"https:\/\/www.vailhealth.org\/about\/doctor-directory\/"},{"@type":"ListItem","position":3,"name":"Grant Rynn"}]},{"@type":"WebSite","@id":"https:\/\/www.vailhealth.org\/#website","url":"https:\/\/www.vailhealth.org\/","name":"Vail Salud","description":"","publisher":{"@id":"https:\/\/www.vailhealth.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vailhealth.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.vailhealth.org\/#organization","name":"Vail Salud","url":"https:\/\/www.vailhealth.org\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.vailhealth.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2026\/03\/layouthorizontal-colorfull.png","contentUrl":"https:\/\/www.vailhealth.org\/wp-content\/uploads\/2026\/03\/layouthorizontal-colorfull.png","width":341,"height":64,"caption":"Vail Health"},"image":{"@id":"https:\/\/www.vailhealth.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VailHealth\/"]}]}},"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"Vail Health","distributor_original_site_url":"https:\/\/www.vailhealth.org\/es","push-errors":false,"_links":{"self":[{"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/about\/doctor-directory\/3617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/about\/doctor-directory"}],"about":[{"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/types\/staff"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/media\/6347"}],"wp:attachment":[{"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/media?parent=3617"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/tags?post=3617"},{"taxonomy":"staff-specialties","embeddable":true,"href":"https:\/\/www.vailhealth.org\/es\/wp-json\/wp\/v2\/staff-specialties?post=3617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}